{"id":3634,"date":"2021-03-15T16:19:25","date_gmt":"2021-03-15T16:19:25","guid":{"rendered":"https:\/\/viktor-solothurn.ch\/datenschutzerklaerung\/"},"modified":"2021-12-13T20:07:04","modified_gmt":"2021-12-13T20:07:04","slug":"declaration-de-confidentialite","status":"publish","type":"page","link":"https:\/\/viktor-solothurn.ch\/fr\/declaration-de-confidentialite\/","title":{"rendered":"D\u00e9claration de confidentialit\u00e9"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Wer wir sind<\/h2><p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Die Adresse unserer Website ist: http:\/\/baseltor.test.<\/p><h2 class=\"wp-block-heading\">Kommentare<\/h2><p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Wenn Besucher Kommentare auf der Website schreiben, sammeln wir die Daten, die im Kommentar-Formular angezeigt werden, ausserdem die IP-Adresse des Besuchers und den User-Agent-String (damit wird der Browser identifiziert), um die Erkennung von Spam zu unterst\u00fctzen.<\/p><p>Aus Ihrer E-Mail-Adresse kann eine anonymisierte Zeichenfolge erstellt (auch Hash genannt) und dem Gravatar-Dienst \u00fcbergeben werden, um zu pr\u00fcfen, ob Sie diesen benutzt. Die Datenschutzerkl\u00e4rung des Gravatar-Dienstes finden Sie hier: https:\/\/automattic.com\/privacy\/. Nachdem Ihr Kommentar freigegeben wurde, ist Ihr Profilbild \u00f6ffentlich im Kontext Ihres Kommentars sichtbar.<\/p><h2 class=\"wp-block-heading\">Medien<\/h2><p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Wenn Sie ein registrierter Benutzer sind und Fotos auf diese Website laden, sollten Sie vermeiden, Fotos mit einem EXIF-GPS-Standort hochzuladen. Besucher dieser Website k\u00f6nnten Fotos, die auf dieser Website gespeichert sind, downloaden und deren Standort-Informationen extrahieren.<\/p><h2 class=\"wp-block-heading\">Cookies<\/h2><p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Wenn Sie einen Kommentar auf unserer Website schreiben, kann das eine Einwilligung sein, Ihren Namen, E-Mail-Adresse und Website in Cookies zu speichern. Dies ist eine Komfortfunktion, damit Sie nicht, wenn Sie einen weiteren Kommentar schreiben, all diese Daten erneut eingeben m\u00fcssen. Diese Cookies werden ein Jahr lang gespeichert.<\/p><p>Falls Sie ein Konto haben und Sie sich auf dieser Website anmelden, werden wir ein tempor\u00e4res Cookie setzen, um festzustellen, ob Ihr Browser Cookies akzeptiert. Dieses Cookie enth\u00e4lt keine personenbezogenen Daten und wird verworfen, wenn Sie Ihren Browser schliessen.<\/p><p>Wenn Sie sich anmelden, werden wir einige Cookies einrichten, um Ihre Anmeldeinformationen und Anzeigeoptionen zu speichern. Anmelde-Cookies verfallen nach zwei Tagen und Cookies f\u00fcr die Anzeigeoptionen nach einem Jahr. Falls Sie bei der Anmeldung \u00abAngemeldet bleiben\u00bb ausw\u00e4hlen, wird Ihre Anmeldung zwei Wochen lang aufrechterhalten. Mit der Abmeldung aus Ihrem Konto werden die Anmelde-Cookies gel\u00f6scht.<\/p><p>Wenn Sie einen Artikel bearbeiten oder ver\u00f6ffentlichen, wird ein zus\u00e4tzlicher Cookie in Ihrem Browser gespeichert. Dieser Cookie enth\u00e4lt keine personenbezogenen Daten und verweist nur auf die Beitrags-ID des Artikels, den Sie gerade bearbeitet haben. Der Cookie verf\u00e4llt nach einem Tag.<\/p><h2 class=\"wp-block-heading\">Eingebettete Inhalte von anderen Websites<\/h2><p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Beitr\u00e4ge auf dieser Website k\u00f6nnen eingebettete Inhalte beinhalten (z.&nbsp;B. Videos, Bilder, Beitr\u00e4ge etc.). Eingebettete Inhalte von anderen Websites verhalten sich exakt so, als ob der Besucher die andere Website besucht h\u00e4tte.<\/p><p>Diese Websites k\u00f6nnen Daten \u00fcber Sie sammeln, Cookies benutzen, zus\u00e4tzliche Tracking-Dienste von Dritten einbetten und Ihre Interaktion mit diesem eingebetteten Inhalt aufzeichnen, inklusive Ihrer Interaktion mit dem eingebetteten Inhalt, falls Sie ein Konto haben und auf dieser Website angemeldet sind.<\/p><h2 class=\"wp-block-heading\">Mit wem wir Ihre Daten teilen<\/h2><p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Wenn Sie eine Zur\u00fccksetzung des Passworts beantragen, wird Ihre IP-Adresse in der E-Mail zur Zur\u00fccksetzung enthalten sein.<\/p><h2 class=\"wp-block-heading\">Wie lange wir Ihre Daten speichern<\/h2><p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Wenn Sie einen Kommentar schreiben, wird dieser inklusive Metadaten zeitlich unbegrenzt gespeichert. Auf diese Art k\u00f6nnen wir Folgekommentare automatisch erkennen und freigeben, anstatt sie in einer Moderations-Warteschlange festzuhalten.<\/p><p>F\u00fcr Benutzer, die sich auf unserer Website registrieren, speichern wir zus\u00e4tzlich die pers\u00f6nlichen Informationen, die sie in ihren Benutzerprofilen angeben. Alle Benutzer k\u00f6nnen jederzeit ihre pers\u00f6nlichen Informationen einsehen, ver\u00e4ndern oder l\u00f6schen (der Benutzername kann nicht ver\u00e4ndert werden). Administratoren der Website k\u00f6nnen diese Informationen ebenfalls einsehen und ver\u00e4ndern.<\/p><h2 class=\"wp-block-heading\">Welche Rechte Sie an Ihren Daten haben<\/h2><p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Wenn Sie ein Konto auf dieser Website besitzen oder Kommentare geschrieben haben, k\u00f6nnen Sie einen Export Ihrer personenbezogenen Daten bei uns anfordern, inklusive aller Daten, die Sie uns mitgeteilt haben. Dar\u00fcber hinaus k\u00f6nnen Sie die L\u00f6schung aller personenbezogenen Daten, die wir von Ihnen gespeichert haben, anfordern. Dies umfasst nicht die Daten, die wir aufgrund administrativer, rechtlicher oder sicherheitsrelevanter Notwendigkeiten aufbewahren m\u00fcssen.<\/p><h2 class=\"wp-block-heading\">Wohin wir Ihre Daten senden<\/h2><p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Besucher-Kommentare k\u00f6nnten von einem automatisierten Dienst zur Spam-Erkennung untersucht werden.<\/p>","protected":false},"excerpt":{"rendered":"<p>Wer wir sind Textvorschlag: Die Adresse unserer Website ist: http:\/\/baseltor.test. Kommentare Textvorschlag: Wenn Besucher Kommentare auf der Website schreiben, sammeln wir die Daten, die im Kommentar-Formular angezeigt werden, ausserdem die IP-Adresse des Besuchers und den User-Agent-String (damit wird der Browser identifiziert), um die Erkennung von Spam zu unterst\u00fctzen. Aus Ihrer E-Mail-Adresse kann eine anonymisierte Zeichenfolge &hellip; <a href=\"https:\/\/viktor-solothurn.ch\/fr\/declaration-de-confidentialite\/\">Continued<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":47,"comment_status":"closed","ping_status":"closed","template":"views\/template-custom.blade.php","meta":{"_acf_changed":false,"inline_featured_image":false},"class_list":["post-3634","page","type-page","status-publish","hentry"],"acf":{"text-header":{"text":"<h1>D\u00e9claration de confidentialit\u00e9<\/h1>\n<p>Le service responsable au sens des lois sur la protection des donn\u00e9es, en particulier du r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD) de l&#8217;UE, est :<\/p>\n<p class=\"p1\">VIKTOR<br \/>\nGurzelngasse 1<br \/>\n4500 Solothurn<br \/>\nSuisse<br \/>\n<span class=\"s1\">T\u00e9l\u00e9phone\u00a0<a href=\"tel:+41326220114\">+41 32 622 01 14<\/a><\/span><\/p>\n"},"text_header":{"text-header":{"text":"<h1>D\u00e9claration de confidentialit\u00e9<\/h1>\n<p>Le service responsable au sens des lois sur la protection des donn\u00e9es, en particulier du r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD) de l&#8217;UE, est :<\/p>\n<p class=\"p1\">VIKTOR<br \/>\nGurzelngasse 1<br \/>\n4500 Solothurn<br \/>\nSuisse<br \/>\n<span class=\"s1\">T\u00e9l\u00e9phone\u00a0<a href=\"tel:+41326220114\">+41 32 622 01 14<\/a><\/span><\/p>\n"}},"elements":[{"acf_fc_layout":"wysiwyg","text":"<h2>Vos droits en tant que personne concern\u00e9e<\/h2>\n<p>Vous pouvez \u00e0 tout moment exercer les droits suivants en utilisant les coordonn\u00e9es indiqu\u00e9es de notre responsable de la protection des donn\u00e9es :<\/p>\n<ul>\n<li>Renseignements sur vos donn\u00e9es enregistr\u00e9es chez nous et sur leur traitement,<\/li>\n<li>Rectification des donn\u00e9es \u00e0 caract\u00e8re personnel inexactes,<\/li>\n<li>Suppression des donn\u00e9es que nous d\u00e9tenons \u00e0 votre sujet,<\/li>\n<li>la limitation du traitement des donn\u00e9es, dans la mesure o\u00f9 nous ne sommes pas encore autoris\u00e9s \u00e0 supprimer vos donn\u00e9es en raison d&#8217;obligations l\u00e9gales,<\/li>\n<li>vous opposer au traitement de vos donn\u00e9es par nos soins et<\/li>\n<li>la portabilit\u00e9 des donn\u00e9es, dans la mesure o\u00f9 vous avez consenti au traitement des donn\u00e9es ou conclu un contrat avec nous.<\/li>\n<\/ul>\n<p>Si vous nous avez donn\u00e9 votre consentement, vous pouvez le r\u00e9voquer \u00e0 tout moment avec effet pour l&#8217;avenir.<\/p>\n<p>Vous pouvez \u00e0 tout moment d\u00e9poser une plainte aupr\u00e8s de l&#8217;autorit\u00e9 de surveillance dont vous d\u00e9pendez. L&#8217;autorit\u00e9 de contr\u00f4le comp\u00e9tente d\u00e9pend de votre province de r\u00e9sidence, de votre travail ou de la violation pr\u00e9sum\u00e9e. Vous trouverez une liste des autorit\u00e9s de surveillance (pour le secteur non public) avec leur adresse \u00e0 l&#8217;adresse suivante :\u00a0<a href=\"https:\/\/www.bfdi.bund.de\/DE\/Infothek\/Anschriften_Links\/anschriften_links-node.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.bfdi.bund.de\/DE\/Infothek\/Anschriften_Links\/anschriften_links-node.html<\/a>.<\/p>\n<h2>Finalit\u00e9s du traitement des donn\u00e9es par le service responsable et par des tiers<\/h2>\n<p>Nous ne traitons vos donn\u00e9es personnelles qu&#8217;aux fins mentionn\u00e9es dans la pr\u00e9sente d\u00e9claration de confidentialit\u00e9. Vos donn\u00e9es personnelles ne sont pas transmises \u00e0 des tiers \u00e0 des fins autres que celles mentionn\u00e9es. Nous ne transmettons vos donn\u00e9es personnelles \u00e0 des tiers que si:<\/p>\n<ul>\n<li>vous avez donn\u00e9 votre consentement explicite \u00e0 cet effet<\/li>\n<li>le traitement est n\u00e9cessaire \u00e0 l&#8217;ex\u00e9cution d&#8217;un contrat avec vous,<\/li>\n<li>le traitement est n\u00e9cessaire au respect d&#8217;une obligation l\u00e9gale,<\/li>\n<\/ul>\n<p>le traitement est n\u00e9cessaire \u00e0 la sauvegarde d&#8217;int\u00e9r\u00eats l\u00e9gitimes et qu&#8217;il n&#8217;existe aucune raison de penser que vous avez un int\u00e9r\u00eat l\u00e9gitime pr\u00e9pond\u00e9rant \u00e0 ce que vos donn\u00e9es ne soient pas divulgu\u00e9es.<\/p>\n<h2>Suppression ou blocage des donn\u00e9es<\/h2>\n<p>Nous respectons les principes de pr\u00e9vention et d&#8217;\u00e9conomie des donn\u00e9es. Nous ne conservons donc vos donn\u00e9es personnelles qu&#8217;aussi longtemps que cela est n\u00e9cessaire pour atteindre les objectifs mentionn\u00e9s ici ou comme le pr\u00e9voient les multiples d\u00e9lais de conservation pr\u00e9vus par le l\u00e9gislateur. Apr\u00e8s la disparition de la finalit\u00e9 respective ou l&#8217;expiration de ces d\u00e9lais, les donn\u00e9es correspondantes sont bloqu\u00e9es ou effac\u00e9es de mani\u00e8re routini\u00e8re et conform\u00e9ment aux prescriptions l\u00e9gales.<\/p>\n<h2>Collecte d&#8217;informations g\u00e9n\u00e9rales lors de la visite de notre site web<\/h2>\n<p>Lorsque vous acc\u00e9dez \u00e0 notre site web, des informations de nature g\u00e9n\u00e9rale sont automatiquement collect\u00e9es au moyen d&#8217;un cookie. Ces informations (fichiers journaux du serveur) contiennent par exemple le type de navigateur web, le syst\u00e8me d&#8217;exploitation utilis\u00e9, le nom de domaine de votre fournisseur de services Internet et d&#8217;autres informations similaires. Il s&#8217;agit exclusivement d&#8217;informations qui ne permettent pas de tirer des conclusions sur votre personne.<\/p>\n<p>Ces informations sont techniquement n\u00e9cessaires pour fournir correctement les contenus de pages web que vous avez demand\u00e9s et sont obligatoires lorsque vous utilisez Internet. Elles sont notamment trait\u00e9es aux fins suivantes :<\/p>\n<ul>\n<li>Assurer une connexion sans probl\u00e8me du site web,<\/li>\n<li>Assurer une bonne utilisation de notre site web,<\/li>\n<li>l&#8217;\u00e9valuation de la s\u00e9curit\u00e9 et de la stabilit\u00e9 du syst\u00e8me, et<\/li>\n<li>\u00e0 d&#8217;autres fins administratives.<\/li>\n<\/ul>\n<p>Le traitement de vos donn\u00e9es personnelles se fonde sur notre int\u00e9r\u00eat l\u00e9gitime d\u00e9coulant des objectifs de collecte de donn\u00e9es susmentionn\u00e9s. Nous n&#8217;utilisons pas vos donn\u00e9es pour tirer des conclusions sur votre personne. Les destinataires des donn\u00e9es sont uniquement le service responsable et, le cas \u00e9ch\u00e9ant, les sous-traitants.<\/p>\n<p>Les informations anonymes de ce type sont \u00e9ventuellement \u00e9valu\u00e9es statistiquement par nos soins afin d&#8217;optimiser notre pr\u00e9sence sur Internet et la technique qui la sous-tend.<\/p>\n<h2>Cookies<\/h2>\n<p>Comme de nombreux autres sites web, nous utilisons \u00e9galement des &#8220;cookies&#8221;. Les cookies sont de petits fichiers texte qui sont transf\u00e9r\u00e9s sur votre disque dur par un serveur de site web. Cela nous permet d&#8217;obtenir automatiquement certaines donn\u00e9es telles que l&#8217;adresse IP, le navigateur utilis\u00e9, le syst\u00e8me d&#8217;exploitation et votre connexion \u00e0 Internet.<\/p>\n<p>Les cookies ne peuvent pas \u00eatre utilis\u00e9s pour lancer des programmes ou transmettre des virus \u00e0 un ordinateur. Gr\u00e2ce aux informations contenues dans les cookies, nous pouvons vous faciliter la navigation et vous permettre d&#8217;afficher correctement nos pages web.<\/p>\n<p>En aucun cas, les donn\u00e9es que nous collectons ne sont transmises \u00e0 des tiers ou un lien avec des donn\u00e9es personnelles n&#8217;est \u00e9tabli sans votre consentement.<\/p>\n<p>Bien entendu, vous pouvez en principe consulter notre site web sans cookies. Les navigateurs Internet sont r\u00e9guli\u00e8rement configur\u00e9s pour accepter les cookies. En g\u00e9n\u00e9ral, vous pouvez \u00e0 tout moment d\u00e9sactiver l&#8217;utilisation de cookies via les param\u00e8tres de votre navigateur. Veuillez utiliser les fonctions d&#8217;aide de votre navigateur Internet pour savoir comment modifier ces param\u00e8tres. Veuillez noter que certaines fonctions de notre site web peuvent ne pas fonctionner si vous avez d\u00e9sactiv\u00e9 l&#8217;utilisation de cookies.<\/p>\n<h2>Cryptage SSL<\/h2>\n<p>Afin de prot\u00e9ger la s\u00e9curit\u00e9 de vos donn\u00e9es lors de leur transmission, nous utilisons des proc\u00e9dures de cryptage conformes \u00e0 l&#8217;\u00e9tat actuel de la technique (par ex. SSL) via HTTPS.<\/p>\n<h2>Newsletter<\/h2>\n<p>Sur la base de votre consentement explicite, nous vous envoyons r\u00e9guli\u00e8rement notre newsletter ou des informations comparables par e-mail \u00e0 l&#8217;adresse e-mail que vous avez indiqu\u00e9e.<\/p>\n<p>Pour recevoir la newsletter, il suffit d&#8217;indiquer votre adresse e-mail. Lorsque vous vous inscrivez pour recevoir notre newsletter, les donn\u00e9es que vous fournissez sont utilis\u00e9es exclusivement \u00e0 cette fin. Les abonn\u00e9s peuvent \u00e9galement \u00eatre inform\u00e9s par e-mail de circonstances pertinentes pour le service ou l&#8217;inscription (par exemple, modifications de l&#8217;offre de la newsletter ou circonstances techniques).<\/p>\n<p>Pour que l&#8217;inscription soit effective, nous avons besoin d&#8217;une adresse e-mail valide. Afin de v\u00e9rifier qu&#8217;une inscription est effectivement effectu\u00e9e par le propri\u00e9taire d&#8217;une adresse e-mail, nous utilisons la proc\u00e9dure &#8220;double-opt-in&#8221;. Pour ce faire, nous enregistrons la commande de la newsletter, l&#8217;envoi d&#8217;un e-mail de confirmation et la r\u00e9ception de la r\u00e9ponse ainsi demand\u00e9e. Aucune autre donn\u00e9e n&#8217;est collect\u00e9e. Les donn\u00e9es sont utilis\u00e9es exclusivement pour l&#8217;envoi de la newsletter et ne sont pas transmises \u00e0 des tiers.<\/p>\n<p>Vous pouvez \u00e0 tout moment r\u00e9voquer votre consentement \u00e0 l&#8217;enregistrement de vos donn\u00e9es personnelles et \u00e0 leur utilisation pour l&#8217;envoi de la newsletter. Vous trouverez un lien \u00e0 cet effet dans chaque newsletter. Vous pouvez \u00e9galement vous d\u00e9sinscrire \u00e0 tout moment directement sur ce site web ou nous faire part de votre souhait en utilisant l&#8217;option de contact indiqu\u00e9e \u00e0 la fin des pr\u00e9sentes informations sur la protection des donn\u00e9es.<\/p>\n<h2>Formulaire de contact<\/h2>\n<p>Si vous nous contactez par e-mail ou via le formulaire de contact pour des questions de toute nature, vous nous donnez votre accord volontaire pour la prise de contact. Pour cela, il est n\u00e9cessaire d&#8217;indiquer une adresse e-mail valide. Celle-ci sert \u00e0 l&#8217;attribution de la demande et \u00e0 la r\u00e9ponse ult\u00e9rieure \u00e0 celle-ci. L&#8217;indication d&#8217;autres donn\u00e9es est facultative. Les donn\u00e9es que vous fournissez sont enregistr\u00e9es dans le but de traiter la demande et pour d&#8217;\u00e9ventuelles questions de suivi. Les donn\u00e9es personnelles sont automatiquement supprim\u00e9es apr\u00e8s l&#8217;ex\u00e9cution de votre demande.<\/p>\n<h2>Utilisation de Google Analytics<\/h2>\n<p>Ce site web utilise Google Analytics, un service d&#8217;analyse web de Google Inc. (ci-apr\u00e8s : Google). Google Analytics utilise des &#8220;cookies&#8221;, c&#8217;est-\u00e0-dire des fichiers texte qui sont enregistr\u00e9s sur votre ordinateur et qui permettent d&#8217;analyser votre utilisation du site web. Les informations g\u00e9n\u00e9r\u00e9es par le cookie concernant votre utilisation de ce site web sont g\u00e9n\u00e9ralement transmises \u00e0 un serveur de Google aux \u00c9tats-Unis et y sont enregistr\u00e9es. En raison de l&#8217;activation de l&#8217;anonymisation IP sur ces pages web, votre adresse IP sera toutefois abr\u00e9g\u00e9e par Google au sein des \u00c9tats membres de l&#8217;Union europ\u00e9enne ou dans d&#8217;autres \u00c9tats signataires de l&#8217;accord sur l&#8217;Espace \u00e9conomique europ\u00e9en. Ce n&#8217;est que dans des cas exceptionnels que l&#8217;adresse IP compl\u00e8te est transmise \u00e0 un serveur de Google aux \u00c9tats-Unis et y est abr\u00e9g\u00e9e. Google utilisera ces informations pour le compte de l&#8217;exploitant de ce site web afin d&#8217;\u00e9valuer votre utilisation du site web, de compiler des rapports sur les activit\u00e9s du site web et de fournir \u00e0 l&#8217;exploitant du site web d&#8217;autres services li\u00e9s \u00e0 l&#8217;utilisation du site web et d&#8217;Internet. L&#8217;adresse IP transmise par votre navigateur dans le cadre de Google Analytics ne sera pas recoup\u00e9e avec d&#8217;autres donn\u00e9es de Google.<\/p>\n<p>Les objectifs du traitement des donn\u00e9es sont l&#8217;\u00e9valuation de l&#8217;utilisation du site web et la compilation de rapports sur les activit\u00e9s du site web. D&#8217;autres services connexes doivent ensuite \u00eatre fournis sur la base de l&#8217;utilisation du site web et d&#8217;Internet. Le traitement repose sur l&#8217;int\u00e9r\u00eat l\u00e9gitime de l&#8217;exploitant du site web.<\/p>\n<p>Vous pouvez emp\u00eacher l&#8217;enregistrement des cookies en param\u00e9trant votre navigateur en cons\u00e9quence ; nous attirons toutefois votre attention sur le fait que, dans ce cas, vous ne pourrez peut-\u00eatre pas utiliser toutes les fonctions de ce site web dans leur int\u00e9gralit\u00e9. Vous pouvez en outre emp\u00eacher la saisie par Google des donn\u00e9es g\u00e9n\u00e9r\u00e9es par le cookie et relatives \u00e0 votre utilisation du site web (y compris votre adresse IP) ainsi que le traitement de ces donn\u00e9es par Google en t\u00e9l\u00e9chargeant et en installant le plug-in de navigateur disponible sous le lien suivant:\u00a0<a href=\"http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener\">Browser Add On zur Deaktivierung von Google Analytics<\/a>.<\/p>\n<p>En plus ou comme alternative au module compl\u00e9mentaire du navigateur, vous pouvez emp\u00eacher le suivi par Google Analytics sur nos pages en cliquant sur ce lien. Un cookie opt-out sera alors install\u00e9 sur votre appareil. Cela emp\u00eachera \u00e0 l&#8217;avenir la saisie par Google Analytics pour ce site web et pour ce navigateur, tant que le cookie reste install\u00e9 dans votre navigateur.<\/p>\n<h2>Utilisation de biblioth\u00e8ques de scripts (Google Webfonts)<\/h2>\n<p>Afin d&#8217;afficher correctement et graphiquement nos contenus sur tous les navigateurs, nous utilisons sur ce site des biblioth\u00e8ques de scripts et des biblioth\u00e8ques de polices telles que Google Webfonts <a href=\"https:\/\/www.google.com\/webfonts\/).\">(https:\/\/www.google.com\/webfonts\/<\/a>). Les Google Webfonts sont transf\u00e9r\u00e9es dans le cache de votre navigateur afin d&#8217;\u00e9viter des chargements r\u00e9p\u00e9t\u00e9s. Si le navigateur ne prend pas en charge les Google Webfonts ou en interdit l&#8217;acc\u00e8s, les contenus sont affich\u00e9s dans une police standard.<\/p>\n<p>L&#8217;appel de biblioth\u00e8ques de scripts ou de polices d\u00e9clenche automatiquement une connexion avec l&#8217;exploitant de la biblioth\u00e8que. Il est th\u00e9oriquement possible que les exploitants de ces biblioth\u00e8ques collectent des donn\u00e9es, mais on ne sait pas actuellement si et, le cas \u00e9ch\u00e9ant, \u00e0 quelles fins.<\/p>\n<p>Vous trouverez ici la politique de confidentialit\u00e9 de l&#8217;exploitant de la biblioth\u00e8que, Google:\u00a0<a href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com\/policies\/privacy\/<\/a><\/p>\n<h2>Utilisation d&#8217;Adobe Typekit<\/h2>\n<p>Nous utilisons Adobe Typekit pour la conception visuelle de notre site web. Typekit est un service d&#8217;Adobe Systems Software Ireland Ltd. qui nous permet d&#8217;acc\u00e9der \u00e0 une biblioth\u00e8que de polices. Pour int\u00e9grer les polices que nous utilisons, votre navigateur doit \u00e9tablir une connexion avec un serveur d&#8217;Adobe aux \u00c9tats-Unis et t\u00e9l\u00e9charger la police n\u00e9cessaire pour notre site web. Adobe re\u00e7oit ainsi l&#8217;information que notre site web a \u00e9t\u00e9 appel\u00e9 par votre adresse IP. Vous trouverez de plus amples informations sur Adobe Typekit dans la d\u00e9claration de protection des donn\u00e9es d&#8217;Adobe, que vous pouvez consulter ici:\u00a0<a href=\"http:\/\/www.adobe.com\/privacy\/typekit.html\" target=\"_blank\" rel=\"noopener\">www.adobe.com\/privacy\/typekit.html<\/a><\/p>\n<h2>Utilisation de Google Maps<\/h2>\n<p>Ce site web utilise l&#8217;API Google Maps pour repr\u00e9senter visuellement des informations g\u00e9ographiques. Lors de l&#8217;utilisation de Google Maps, Google collecte, traite et utilise \u00e9galement des donn\u00e9es relatives \u00e0 l&#8217;utilisation des fonctions cartographiques par les visiteurs. Vous trouverez de plus amples informations sur le traitement des donn\u00e9es par Google dans <a href=\"http:\/\/www.google.com\/privacypolicy.html\" target=\"_blank\" rel=\"noopener\">les informations sur la protection des donn\u00e9es de Google<\/a>. Vous pouvez \u00e9galement y modifier vos param\u00e8tres personnels de protection des donn\u00e9es dans le centre de protection des donn\u00e9es.<\/p>\n<p>Vous trouverez ici des instructions d\u00e9taill\u00e9es sur la gestion de vos propres donn\u00e9es en relation avec les <a href=\"http:\/\/www.dataliberation.org\/\" target=\"_blank\" rel=\"noopener\">produits Google<\/a>.<\/p>\n<h2>Vid\u00e9os YouTube int\u00e9gr\u00e9es<\/h2>\n<p>Sur certaines de nos pages web, nous int\u00e9grons des vid\u00e9os Youtube. L&#8217;exploitant des plugins correspondants est YouTube, LLC, 901 Cherry Ave., San Bruno, CA 94066, USA. Lorsque vous visitez une page avec le plug-in YouTube, une connexion est \u00e9tablie avec les serveurs de Youtube. Youtube est alors inform\u00e9 des pages que vous visitez. Si vous \u00eates connect\u00e9 \u00e0 votre compte Youtube, Youtube peut vous attribuer personnellement votre comportement de navigation. Vous pouvez \u00e9viter cela en vous d\u00e9connectant au pr\u00e9alable de votre compte Youtube.<\/p>\n<p>Lorsqu&#8217;une vid\u00e9o Youtube est lanc\u00e9e, le fournisseur utilise des cookies qui collectent des informations sur le comportement de l&#8217;utilisateur.<\/p>\n<p>Les personnes qui ont d\u00e9sactiv\u00e9 l&#8217;enregistrement de cookies pour le programme publicitaire de Google ne doivent pas s&#8217;attendre \u00e0 recevoir de tels cookies lorsqu&#8217;elles visionnent des vid\u00e9os Youtube. Youtube enregistre \u00e9galement des informations d&#8217;utilisation non personnelles dans d&#8217;autres cookies. Si vous souhaitez emp\u00eacher cela, vous devez bloquer le stockage des cookies dans votre navigateur.<\/p>\n<p>Pour plus d&#8217;informations sur la protection des donn\u00e9es sur &#8220;Youtube&#8221;, veuillez consulter la d\u00e9claration de confidentialit\u00e9 du fournisseur \u00e0 l&#8217;adresse suivante:\u00a0<a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.de\/intl\/de\/policies\/privacy\/<\/a><\/p>\n<h2>Social Plugins<\/h2>\n<p>Des plugins sociaux des fournisseurs mentionn\u00e9s ci-dessous sont utilis\u00e9s sur nos pages web. Vous pouvez reconna\u00eetre les plugins au fait qu&#8217;ils sont marqu\u00e9s du logo correspondant.<\/p>\n<p>Par le biais de ces plug-ins, des informations, parmi lesquelles peuvent figurer des donn\u00e9es personnelles, peuvent \u00eatre envoy\u00e9es \u00e0 l&#8217;exploitant du service et \u00e9ventuellement utilis\u00e9es par celui-ci. Nous emp\u00eachons la saisie et la transmission inconscientes et involontaires de donn\u00e9es au fournisseur de services par une solution \u00e0 deux clics. Pour activer un plugin social souhait\u00e9, il faut d&#8217;abord l&#8217;activer en cliquant sur le bouton correspondant. Ce n&#8217;est que par cette activation du plug-in que la saisie des informations et leur transmission au fournisseur de services sont d\u00e9clench\u00e9es. Nous ne collectons pas nous-m\u00eames de donn\u00e9es personnelles par le biais des plugins sociaux ou de leur utilisation.<\/p>\n<p>Nous n&#8217;avons aucune influence sur les donn\u00e9es saisies par un plugin activ\u00e9 et sur la mani\u00e8re dont elles sont utilis\u00e9es par le fournisseur. Actuellement, il faut partir du principe qu&#8217;une connexion directe aux services du fournisseur est \u00e9tablie et qu&#8217;au moins l&#8217;adresse IP et des informations relatives \u00e0 l&#8217;appareil sont saisies et utilis\u00e9es. Il est \u00e9galement possible que les fournisseurs de services tentent de stocker des cookies sur l&#8217;ordinateur utilis\u00e9. Pour savoir quelles donn\u00e9es concr\u00e8tes sont saisies et comment elles sont utilis\u00e9es, veuillez consulter les informations relatives \u00e0 la protection des donn\u00e9es du fournisseur de services concern\u00e9. Remarque : si vous \u00eates connect\u00e9 \u00e0 Facebook en m\u00eame temps, Facebook peut vous identifier comme visiteur d&#8217;une certaine page.<\/p>\n<p>Nous avons int\u00e9gr\u00e9 sur notre site web les boutons de m\u00e9dias sociaux des entreprises suivantes:<\/p>\n<h2>Modification de notre politique de confidentialit\u00e9<\/h2>\n<p>Nous nous r\u00e9servons le droit d&#8217;adapter la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es afin qu&#8217;elle soit toujours conforme aux exigences l\u00e9gales actuelles ou afin de mettre en \u0153uvre les modifications de nos prestations dans la d\u00e9claration de protection des donn\u00e9es, par exemple lors de l&#8217;introduction de nouveaux services. La nouvelle d\u00e9claration de protection des donn\u00e9es s&#8217;appliquera alors \u00e0 votre nouvelle visite.<\/p>\n<h2>Questions au d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es<\/h2>\n<p>Si vous avez des questions concernant la protection des donn\u00e9es, veuillez nous envoyer un e-mail ou vous adresser directement \u00e0 la personne responsable de la protection des donn\u00e9es dans notre organisation :<\/p>\n<p class=\"p1\">VIKTOR<br \/>\nGurzelngasse 1<br \/>\n4500 Solothurn<br \/>\nSuisse<br \/>\n<span class=\"s1\">T\u00e9l\u00e9phone\u00a0<a href=\"tel:+41326220114\">+41 32 622 01 14<\/a><\/span><\/p>\n"}],"home_elements":{"elements":[{"acf_fc_layout":"wysiwyg","text":"<h2>Vos droits en tant que personne concern\u00e9e<\/h2>\n<p>Vous pouvez \u00e0 tout moment exercer les droits suivants en utilisant les coordonn\u00e9es indiqu\u00e9es de notre responsable de la protection des donn\u00e9es :<\/p>\n<ul>\n<li>Renseignements sur vos donn\u00e9es enregistr\u00e9es chez nous et sur leur traitement,<\/li>\n<li>Rectification des donn\u00e9es \u00e0 caract\u00e8re personnel inexactes,<\/li>\n<li>Suppression des donn\u00e9es que nous d\u00e9tenons \u00e0 votre sujet,<\/li>\n<li>la limitation du traitement des donn\u00e9es, dans la mesure o\u00f9 nous ne sommes pas encore autoris\u00e9s \u00e0 supprimer vos donn\u00e9es en raison d&#8217;obligations l\u00e9gales,<\/li>\n<li>vous opposer au traitement de vos donn\u00e9es par nos soins et<\/li>\n<li>la portabilit\u00e9 des donn\u00e9es, dans la mesure o\u00f9 vous avez consenti au traitement des donn\u00e9es ou conclu un contrat avec nous.<\/li>\n<\/ul>\n<p>Si vous nous avez donn\u00e9 votre consentement, vous pouvez le r\u00e9voquer \u00e0 tout moment avec effet pour l&#8217;avenir.<\/p>\n<p>Vous pouvez \u00e0 tout moment d\u00e9poser une plainte aupr\u00e8s de l&#8217;autorit\u00e9 de surveillance dont vous d\u00e9pendez. L&#8217;autorit\u00e9 de contr\u00f4le comp\u00e9tente d\u00e9pend de votre province de r\u00e9sidence, de votre travail ou de la violation pr\u00e9sum\u00e9e. Vous trouverez une liste des autorit\u00e9s de surveillance (pour le secteur non public) avec leur adresse \u00e0 l&#8217;adresse suivante :\u00a0<a href=\"https:\/\/www.bfdi.bund.de\/DE\/Infothek\/Anschriften_Links\/anschriften_links-node.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.bfdi.bund.de\/DE\/Infothek\/Anschriften_Links\/anschriften_links-node.html<\/a>.<\/p>\n<h2>Finalit\u00e9s du traitement des donn\u00e9es par le service responsable et par des tiers<\/h2>\n<p>Nous ne traitons vos donn\u00e9es personnelles qu&#8217;aux fins mentionn\u00e9es dans la pr\u00e9sente d\u00e9claration de confidentialit\u00e9. Vos donn\u00e9es personnelles ne sont pas transmises \u00e0 des tiers \u00e0 des fins autres que celles mentionn\u00e9es. Nous ne transmettons vos donn\u00e9es personnelles \u00e0 des tiers que si:<\/p>\n<ul>\n<li>vous avez donn\u00e9 votre consentement explicite \u00e0 cet effet<\/li>\n<li>le traitement est n\u00e9cessaire \u00e0 l&#8217;ex\u00e9cution d&#8217;un contrat avec vous,<\/li>\n<li>le traitement est n\u00e9cessaire au respect d&#8217;une obligation l\u00e9gale,<\/li>\n<\/ul>\n<p>le traitement est n\u00e9cessaire \u00e0 la sauvegarde d&#8217;int\u00e9r\u00eats l\u00e9gitimes et qu&#8217;il n&#8217;existe aucune raison de penser que vous avez un int\u00e9r\u00eat l\u00e9gitime pr\u00e9pond\u00e9rant \u00e0 ce que vos donn\u00e9es ne soient pas divulgu\u00e9es.<\/p>\n<h2>Suppression ou blocage des donn\u00e9es<\/h2>\n<p>Nous respectons les principes de pr\u00e9vention et d&#8217;\u00e9conomie des donn\u00e9es. Nous ne conservons donc vos donn\u00e9es personnelles qu&#8217;aussi longtemps que cela est n\u00e9cessaire pour atteindre les objectifs mentionn\u00e9s ici ou comme le pr\u00e9voient les multiples d\u00e9lais de conservation pr\u00e9vus par le l\u00e9gislateur. Apr\u00e8s la disparition de la finalit\u00e9 respective ou l&#8217;expiration de ces d\u00e9lais, les donn\u00e9es correspondantes sont bloqu\u00e9es ou effac\u00e9es de mani\u00e8re routini\u00e8re et conform\u00e9ment aux prescriptions l\u00e9gales.<\/p>\n<h2>Collecte d&#8217;informations g\u00e9n\u00e9rales lors de la visite de notre site web<\/h2>\n<p>Lorsque vous acc\u00e9dez \u00e0 notre site web, des informations de nature g\u00e9n\u00e9rale sont automatiquement collect\u00e9es au moyen d&#8217;un cookie. Ces informations (fichiers journaux du serveur) contiennent par exemple le type de navigateur web, le syst\u00e8me d&#8217;exploitation utilis\u00e9, le nom de domaine de votre fournisseur de services Internet et d&#8217;autres informations similaires. Il s&#8217;agit exclusivement d&#8217;informations qui ne permettent pas de tirer des conclusions sur votre personne.<\/p>\n<p>Ces informations sont techniquement n\u00e9cessaires pour fournir correctement les contenus de pages web que vous avez demand\u00e9s et sont obligatoires lorsque vous utilisez Internet. Elles sont notamment trait\u00e9es aux fins suivantes :<\/p>\n<ul>\n<li>Assurer une connexion sans probl\u00e8me du site web,<\/li>\n<li>Assurer une bonne utilisation de notre site web,<\/li>\n<li>l&#8217;\u00e9valuation de la s\u00e9curit\u00e9 et de la stabilit\u00e9 du syst\u00e8me, et<\/li>\n<li>\u00e0 d&#8217;autres fins administratives.<\/li>\n<\/ul>\n<p>Le traitement de vos donn\u00e9es personnelles se fonde sur notre int\u00e9r\u00eat l\u00e9gitime d\u00e9coulant des objectifs de collecte de donn\u00e9es susmentionn\u00e9s. Nous n&#8217;utilisons pas vos donn\u00e9es pour tirer des conclusions sur votre personne. Les destinataires des donn\u00e9es sont uniquement le service responsable et, le cas \u00e9ch\u00e9ant, les sous-traitants.<\/p>\n<p>Les informations anonymes de ce type sont \u00e9ventuellement \u00e9valu\u00e9es statistiquement par nos soins afin d&#8217;optimiser notre pr\u00e9sence sur Internet et la technique qui la sous-tend.<\/p>\n<h2>Cookies<\/h2>\n<p>Comme de nombreux autres sites web, nous utilisons \u00e9galement des &#8220;cookies&#8221;. Les cookies sont de petits fichiers texte qui sont transf\u00e9r\u00e9s sur votre disque dur par un serveur de site web. Cela nous permet d&#8217;obtenir automatiquement certaines donn\u00e9es telles que l&#8217;adresse IP, le navigateur utilis\u00e9, le syst\u00e8me d&#8217;exploitation et votre connexion \u00e0 Internet.<\/p>\n<p>Les cookies ne peuvent pas \u00eatre utilis\u00e9s pour lancer des programmes ou transmettre des virus \u00e0 un ordinateur. Gr\u00e2ce aux informations contenues dans les cookies, nous pouvons vous faciliter la navigation et vous permettre d&#8217;afficher correctement nos pages web.<\/p>\n<p>En aucun cas, les donn\u00e9es que nous collectons ne sont transmises \u00e0 des tiers ou un lien avec des donn\u00e9es personnelles n&#8217;est \u00e9tabli sans votre consentement.<\/p>\n<p>Bien entendu, vous pouvez en principe consulter notre site web sans cookies. Les navigateurs Internet sont r\u00e9guli\u00e8rement configur\u00e9s pour accepter les cookies. En g\u00e9n\u00e9ral, vous pouvez \u00e0 tout moment d\u00e9sactiver l&#8217;utilisation de cookies via les param\u00e8tres de votre navigateur. Veuillez utiliser les fonctions d&#8217;aide de votre navigateur Internet pour savoir comment modifier ces param\u00e8tres. Veuillez noter que certaines fonctions de notre site web peuvent ne pas fonctionner si vous avez d\u00e9sactiv\u00e9 l&#8217;utilisation de cookies.<\/p>\n<h2>Cryptage SSL<\/h2>\n<p>Afin de prot\u00e9ger la s\u00e9curit\u00e9 de vos donn\u00e9es lors de leur transmission, nous utilisons des proc\u00e9dures de cryptage conformes \u00e0 l&#8217;\u00e9tat actuel de la technique (par ex. SSL) via HTTPS.<\/p>\n<h2>Newsletter<\/h2>\n<p>Sur la base de votre consentement explicite, nous vous envoyons r\u00e9guli\u00e8rement notre newsletter ou des informations comparables par e-mail \u00e0 l&#8217;adresse e-mail que vous avez indiqu\u00e9e.<\/p>\n<p>Pour recevoir la newsletter, il suffit d&#8217;indiquer votre adresse e-mail. Lorsque vous vous inscrivez pour recevoir notre newsletter, les donn\u00e9es que vous fournissez sont utilis\u00e9es exclusivement \u00e0 cette fin. Les abonn\u00e9s peuvent \u00e9galement \u00eatre inform\u00e9s par e-mail de circonstances pertinentes pour le service ou l&#8217;inscription (par exemple, modifications de l&#8217;offre de la newsletter ou circonstances techniques).<\/p>\n<p>Pour que l&#8217;inscription soit effective, nous avons besoin d&#8217;une adresse e-mail valide. Afin de v\u00e9rifier qu&#8217;une inscription est effectivement effectu\u00e9e par le propri\u00e9taire d&#8217;une adresse e-mail, nous utilisons la proc\u00e9dure &#8220;double-opt-in&#8221;. Pour ce faire, nous enregistrons la commande de la newsletter, l&#8217;envoi d&#8217;un e-mail de confirmation et la r\u00e9ception de la r\u00e9ponse ainsi demand\u00e9e. Aucune autre donn\u00e9e n&#8217;est collect\u00e9e. Les donn\u00e9es sont utilis\u00e9es exclusivement pour l&#8217;envoi de la newsletter et ne sont pas transmises \u00e0 des tiers.<\/p>\n<p>Vous pouvez \u00e0 tout moment r\u00e9voquer votre consentement \u00e0 l&#8217;enregistrement de vos donn\u00e9es personnelles et \u00e0 leur utilisation pour l&#8217;envoi de la newsletter. Vous trouverez un lien \u00e0 cet effet dans chaque newsletter. Vous pouvez \u00e9galement vous d\u00e9sinscrire \u00e0 tout moment directement sur ce site web ou nous faire part de votre souhait en utilisant l&#8217;option de contact indiqu\u00e9e \u00e0 la fin des pr\u00e9sentes informations sur la protection des donn\u00e9es.<\/p>\n<h2>Formulaire de contact<\/h2>\n<p>Si vous nous contactez par e-mail ou via le formulaire de contact pour des questions de toute nature, vous nous donnez votre accord volontaire pour la prise de contact. Pour cela, il est n\u00e9cessaire d&#8217;indiquer une adresse e-mail valide. Celle-ci sert \u00e0 l&#8217;attribution de la demande et \u00e0 la r\u00e9ponse ult\u00e9rieure \u00e0 celle-ci. L&#8217;indication d&#8217;autres donn\u00e9es est facultative. Les donn\u00e9es que vous fournissez sont enregistr\u00e9es dans le but de traiter la demande et pour d&#8217;\u00e9ventuelles questions de suivi. Les donn\u00e9es personnelles sont automatiquement supprim\u00e9es apr\u00e8s l&#8217;ex\u00e9cution de votre demande.<\/p>\n<h2>Utilisation de Google Analytics<\/h2>\n<p>Ce site web utilise Google Analytics, un service d&#8217;analyse web de Google Inc. (ci-apr\u00e8s : Google). Google Analytics utilise des &#8220;cookies&#8221;, c&#8217;est-\u00e0-dire des fichiers texte qui sont enregistr\u00e9s sur votre ordinateur et qui permettent d&#8217;analyser votre utilisation du site web. Les informations g\u00e9n\u00e9r\u00e9es par le cookie concernant votre utilisation de ce site web sont g\u00e9n\u00e9ralement transmises \u00e0 un serveur de Google aux \u00c9tats-Unis et y sont enregistr\u00e9es. En raison de l&#8217;activation de l&#8217;anonymisation IP sur ces pages web, votre adresse IP sera toutefois abr\u00e9g\u00e9e par Google au sein des \u00c9tats membres de l&#8217;Union europ\u00e9enne ou dans d&#8217;autres \u00c9tats signataires de l&#8217;accord sur l&#8217;Espace \u00e9conomique europ\u00e9en. Ce n&#8217;est que dans des cas exceptionnels que l&#8217;adresse IP compl\u00e8te est transmise \u00e0 un serveur de Google aux \u00c9tats-Unis et y est abr\u00e9g\u00e9e. Google utilisera ces informations pour le compte de l&#8217;exploitant de ce site web afin d&#8217;\u00e9valuer votre utilisation du site web, de compiler des rapports sur les activit\u00e9s du site web et de fournir \u00e0 l&#8217;exploitant du site web d&#8217;autres services li\u00e9s \u00e0 l&#8217;utilisation du site web et d&#8217;Internet. L&#8217;adresse IP transmise par votre navigateur dans le cadre de Google Analytics ne sera pas recoup\u00e9e avec d&#8217;autres donn\u00e9es de Google.<\/p>\n<p>Les objectifs du traitement des donn\u00e9es sont l&#8217;\u00e9valuation de l&#8217;utilisation du site web et la compilation de rapports sur les activit\u00e9s du site web. D&#8217;autres services connexes doivent ensuite \u00eatre fournis sur la base de l&#8217;utilisation du site web et d&#8217;Internet. Le traitement repose sur l&#8217;int\u00e9r\u00eat l\u00e9gitime de l&#8217;exploitant du site web.<\/p>\n<p>Vous pouvez emp\u00eacher l&#8217;enregistrement des cookies en param\u00e9trant votre navigateur en cons\u00e9quence ; nous attirons toutefois votre attention sur le fait que, dans ce cas, vous ne pourrez peut-\u00eatre pas utiliser toutes les fonctions de ce site web dans leur int\u00e9gralit\u00e9. Vous pouvez en outre emp\u00eacher la saisie par Google des donn\u00e9es g\u00e9n\u00e9r\u00e9es par le cookie et relatives \u00e0 votre utilisation du site web (y compris votre adresse IP) ainsi que le traitement de ces donn\u00e9es par Google en t\u00e9l\u00e9chargeant et en installant le plug-in de navigateur disponible sous le lien suivant:\u00a0<a href=\"http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener\">Browser Add On zur Deaktivierung von Google Analytics<\/a>.<\/p>\n<p>En plus ou comme alternative au module compl\u00e9mentaire du navigateur, vous pouvez emp\u00eacher le suivi par Google Analytics sur nos pages en cliquant sur ce lien. Un cookie opt-out sera alors install\u00e9 sur votre appareil. Cela emp\u00eachera \u00e0 l&#8217;avenir la saisie par Google Analytics pour ce site web et pour ce navigateur, tant que le cookie reste install\u00e9 dans votre navigateur.<\/p>\n<h2>Utilisation de biblioth\u00e8ques de scripts (Google Webfonts)<\/h2>\n<p>Afin d&#8217;afficher correctement et graphiquement nos contenus sur tous les navigateurs, nous utilisons sur ce site des biblioth\u00e8ques de scripts et des biblioth\u00e8ques de polices telles que Google Webfonts <a href=\"https:\/\/www.google.com\/webfonts\/).\">(https:\/\/www.google.com\/webfonts\/<\/a>). Les Google Webfonts sont transf\u00e9r\u00e9es dans le cache de votre navigateur afin d&#8217;\u00e9viter des chargements r\u00e9p\u00e9t\u00e9s. Si le navigateur ne prend pas en charge les Google Webfonts ou en interdit l&#8217;acc\u00e8s, les contenus sont affich\u00e9s dans une police standard.<\/p>\n<p>L&#8217;appel de biblioth\u00e8ques de scripts ou de polices d\u00e9clenche automatiquement une connexion avec l&#8217;exploitant de la biblioth\u00e8que. Il est th\u00e9oriquement possible que les exploitants de ces biblioth\u00e8ques collectent des donn\u00e9es, mais on ne sait pas actuellement si et, le cas \u00e9ch\u00e9ant, \u00e0 quelles fins.<\/p>\n<p>Vous trouverez ici la politique de confidentialit\u00e9 de l&#8217;exploitant de la biblioth\u00e8que, Google:\u00a0<a href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com\/policies\/privacy\/<\/a><\/p>\n<h2>Utilisation d&#8217;Adobe Typekit<\/h2>\n<p>Nous utilisons Adobe Typekit pour la conception visuelle de notre site web. Typekit est un service d&#8217;Adobe Systems Software Ireland Ltd. qui nous permet d&#8217;acc\u00e9der \u00e0 une biblioth\u00e8que de polices. Pour int\u00e9grer les polices que nous utilisons, votre navigateur doit \u00e9tablir une connexion avec un serveur d&#8217;Adobe aux \u00c9tats-Unis et t\u00e9l\u00e9charger la police n\u00e9cessaire pour notre site web. Adobe re\u00e7oit ainsi l&#8217;information que notre site web a \u00e9t\u00e9 appel\u00e9 par votre adresse IP. Vous trouverez de plus amples informations sur Adobe Typekit dans la d\u00e9claration de protection des donn\u00e9es d&#8217;Adobe, que vous pouvez consulter ici:\u00a0<a href=\"http:\/\/www.adobe.com\/privacy\/typekit.html\" target=\"_blank\" rel=\"noopener\">www.adobe.com\/privacy\/typekit.html<\/a><\/p>\n<h2>Utilisation de Google Maps<\/h2>\n<p>Ce site web utilise l&#8217;API Google Maps pour repr\u00e9senter visuellement des informations g\u00e9ographiques. Lors de l&#8217;utilisation de Google Maps, Google collecte, traite et utilise \u00e9galement des donn\u00e9es relatives \u00e0 l&#8217;utilisation des fonctions cartographiques par les visiteurs. Vous trouverez de plus amples informations sur le traitement des donn\u00e9es par Google dans <a href=\"http:\/\/www.google.com\/privacypolicy.html\" target=\"_blank\" rel=\"noopener\">les informations sur la protection des donn\u00e9es de Google<\/a>. Vous pouvez \u00e9galement y modifier vos param\u00e8tres personnels de protection des donn\u00e9es dans le centre de protection des donn\u00e9es.<\/p>\n<p>Vous trouverez ici des instructions d\u00e9taill\u00e9es sur la gestion de vos propres donn\u00e9es en relation avec les <a href=\"http:\/\/www.dataliberation.org\/\" target=\"_blank\" rel=\"noopener\">produits Google<\/a>.<\/p>\n<h2>Vid\u00e9os YouTube int\u00e9gr\u00e9es<\/h2>\n<p>Sur certaines de nos pages web, nous int\u00e9grons des vid\u00e9os Youtube. L&#8217;exploitant des plugins correspondants est YouTube, LLC, 901 Cherry Ave., San Bruno, CA 94066, USA. Lorsque vous visitez une page avec le plug-in YouTube, une connexion est \u00e9tablie avec les serveurs de Youtube. Youtube est alors inform\u00e9 des pages que vous visitez. Si vous \u00eates connect\u00e9 \u00e0 votre compte Youtube, Youtube peut vous attribuer personnellement votre comportement de navigation. Vous pouvez \u00e9viter cela en vous d\u00e9connectant au pr\u00e9alable de votre compte Youtube.<\/p>\n<p>Lorsqu&#8217;une vid\u00e9o Youtube est lanc\u00e9e, le fournisseur utilise des cookies qui collectent des informations sur le comportement de l&#8217;utilisateur.<\/p>\n<p>Les personnes qui ont d\u00e9sactiv\u00e9 l&#8217;enregistrement de cookies pour le programme publicitaire de Google ne doivent pas s&#8217;attendre \u00e0 recevoir de tels cookies lorsqu&#8217;elles visionnent des vid\u00e9os Youtube. Youtube enregistre \u00e9galement des informations d&#8217;utilisation non personnelles dans d&#8217;autres cookies. Si vous souhaitez emp\u00eacher cela, vous devez bloquer le stockage des cookies dans votre navigateur.<\/p>\n<p>Pour plus d&#8217;informations sur la protection des donn\u00e9es sur &#8220;Youtube&#8221;, veuillez consulter la d\u00e9claration de confidentialit\u00e9 du fournisseur \u00e0 l&#8217;adresse suivante:\u00a0<a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.de\/intl\/de\/policies\/privacy\/<\/a><\/p>\n<h2>Social Plugins<\/h2>\n<p>Des plugins sociaux des fournisseurs mentionn\u00e9s ci-dessous sont utilis\u00e9s sur nos pages web. Vous pouvez reconna\u00eetre les plugins au fait qu&#8217;ils sont marqu\u00e9s du logo correspondant.<\/p>\n<p>Par le biais de ces plug-ins, des informations, parmi lesquelles peuvent figurer des donn\u00e9es personnelles, peuvent \u00eatre envoy\u00e9es \u00e0 l&#8217;exploitant du service et \u00e9ventuellement utilis\u00e9es par celui-ci. Nous emp\u00eachons la saisie et la transmission inconscientes et involontaires de donn\u00e9es au fournisseur de services par une solution \u00e0 deux clics. Pour activer un plugin social souhait\u00e9, il faut d&#8217;abord l&#8217;activer en cliquant sur le bouton correspondant. Ce n&#8217;est que par cette activation du plug-in que la saisie des informations et leur transmission au fournisseur de services sont d\u00e9clench\u00e9es. Nous ne collectons pas nous-m\u00eames de donn\u00e9es personnelles par le biais des plugins sociaux ou de leur utilisation.<\/p>\n<p>Nous n&#8217;avons aucune influence sur les donn\u00e9es saisies par un plugin activ\u00e9 et sur la mani\u00e8re dont elles sont utilis\u00e9es par le fournisseur. Actuellement, il faut partir du principe qu&#8217;une connexion directe aux services du fournisseur est \u00e9tablie et qu&#8217;au moins l&#8217;adresse IP et des informations relatives \u00e0 l&#8217;appareil sont saisies et utilis\u00e9es. Il est \u00e9galement possible que les fournisseurs de services tentent de stocker des cookies sur l&#8217;ordinateur utilis\u00e9. Pour savoir quelles donn\u00e9es concr\u00e8tes sont saisies et comment elles sont utilis\u00e9es, veuillez consulter les informations relatives \u00e0 la protection des donn\u00e9es du fournisseur de services concern\u00e9. Remarque : si vous \u00eates connect\u00e9 \u00e0 Facebook en m\u00eame temps, Facebook peut vous identifier comme visiteur d&#8217;une certaine page.<\/p>\n<p>Nous avons int\u00e9gr\u00e9 sur notre site web les boutons de m\u00e9dias sociaux des entreprises suivantes:<\/p>\n<h2>Modification de notre politique de confidentialit\u00e9<\/h2>\n<p>Nous nous r\u00e9servons le droit d&#8217;adapter la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es afin qu&#8217;elle soit toujours conforme aux exigences l\u00e9gales actuelles ou afin de mettre en \u0153uvre les modifications de nos prestations dans la d\u00e9claration de protection des donn\u00e9es, par exemple lors de l&#8217;introduction de nouveaux services. La nouvelle d\u00e9claration de protection des donn\u00e9es s&#8217;appliquera alors \u00e0 votre nouvelle visite.<\/p>\n<h2>Questions au d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es<\/h2>\n<p>Si vous avez des questions concernant la protection des donn\u00e9es, veuillez nous envoyer un e-mail ou vous adresser directement \u00e0 la personne responsable de la protection des donn\u00e9es dans notre organisation :<\/p>\n<p class=\"p1\">VIKTOR<br \/>\nGurzelngasse 1<br \/>\n4500 Solothurn<br \/>\nSuisse<br \/>\n<span class=\"s1\">T\u00e9l\u00e9phone\u00a0<a href=\"tel:+41326220114\">+41 32 622 01 14<\/a><\/span><\/p>\n"}]},"seo":{"active":true,"title":"","text":"","image":false,"keywords":""}},"_links":{"self":[{"href":"https:\/\/viktor-solothurn.ch\/fr\/wp-json\/wp\/v2\/pages\/3634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viktor-solothurn.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/viktor-solothurn.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/viktor-solothurn.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/viktor-solothurn.ch\/fr\/wp-json\/wp\/v2\/comments?post=3634"}],"version-history":[{"count":2,"href":"https:\/\/viktor-solothurn.ch\/fr\/wp-json\/wp\/v2\/pages\/3634\/revisions"}],"predecessor-version":[{"id":3636,"href":"https:\/\/viktor-solothurn.ch\/fr\/wp-json\/wp\/v2\/pages\/3634\/revisions\/3636"}],"wp:attachment":[{"href":"https:\/\/viktor-solothurn.ch\/fr\/wp-json\/wp\/v2\/media?parent=3634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}